{"id":3264,"date":"2025-09-26T22:34:03","date_gmt":"2025-09-26T20:34:03","guid":{"rendered":"https:\/\/al-nanteserdre.org\/alm-wp\/?p=3264"},"modified":"2025-09-26T22:36:09","modified_gmt":"2025-09-26T20:36:09","slug":"la-fresque-des-frontieres-planetaires-15-octobre-2025","status":"publish","type":"post","link":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/","title":{"rendered":"La Fresque des fronti\u00e8res plan\u00e9taires &#8211; 15 octobre 2025"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"298\" height=\"169\" src=\"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/09\/Fresque_frontieres_planetaires.png\" alt=\"\" class=\"wp-image-3265\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Mercredi 15 octobre \u00e0 19h<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Salle d&rsquo;activit\u00e9s de l&rsquo;Amicale la\u00efque des Marsauderies<\/strong> &#8211; <strong>Atelier gratuit, sur inscription<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Le cycle de fresques, que vous propose l\u2019amicale pour la troisi\u00e8me ann\u00e9e, d\u00e9marre le 15 octobre avec la fresque des fronti\u00e8res plan\u00e9taire. C&rsquo;est la fresque la plus compl\u00e8te sur les enjeux \u00e9cologiques : outre le climat, on y parle biodiversit\u00e9, cycle de l&rsquo;eau douce, changement d&rsquo;usage des sols&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les enjeux environnementaux sont nombreux et il y a de quoi s&rsquo;y perdre. La fresque des fronti\u00e8res plan\u00e9taires propose aux participants de prendre du recul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inspir\u00e9 de la fresque du climat, la fresque des fronti\u00e8res plan\u00e9taires est un atelier ludique et collaboratif qui s&rsquo;appuie sur 42 cartes visant \u00e0 aborder la question \u00e9cologique dans son ensemble.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">L\u2019inscription est obligatoire &#8211; car le nombre de places est limit\u00e9, en cliquant sur le lien ci-dessous :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/1erdegre.glide.page\/dl\/3b1bc8\/s\/df85fa\/r\/FPLA-h6rRH6f56vR3QpLpw\"><img loading=\"lazy\" decoding=\"async\" width=\"428\" height=\"71\" src=\"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/03\/Bouton_inscription.jpg\" alt=\"\" class=\"wp-image-3112\" srcset=\"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/03\/Bouton_inscription.jpg 428w, https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/03\/Bouton_inscription-300x50.jpg 300w\" sizes=\"auto, (max-width: 428px) 100vw, 428px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Pour tout public \u00e0 partir de 16 ans.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>A bient\u00f4t pour ce nouvel atelier !<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Fresque des fronti\u00e8res plan\u00e9taires &#8211; Salle d&rsquo;activit\u00e9 de l&rsquo;AL des Marsauderies, angle de la rue de Koufra et du Bd Jules Verne &#8211; Bus C1 &#8211; Arr\u00eat Chocolaterie &#8211; Mercredi 15 octobre, de 19h \u00e0 22h.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercredi 15 octobre \u00e0 19h Salle d&rsquo;activit\u00e9s de l&rsquo;Amicale la\u00efque des Marsauderies &#8211; Atelier gratuit, sur inscription Le cycle de fresques, que vous propose l\u2019amicale pour la troisi\u00e8me ann\u00e9e, d\u00e9marre le 15 octobre avec la fresque des fronti\u00e8res plan\u00e9taire. C&rsquo;est la fresque la plus compl\u00e8te sur les enjeux \u00e9cologiques : outre le climat, on y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[],"class_list":["post-3264","post","type-post","status-publish","format-standard","hentry","category-activites","category-manifestations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Fresque des fronti\u00e8res plan\u00e9taires - 15 octobre 2025 - Amicale La\u00efque des Marsauderies<\/title>\n<meta name=\"description\" content=\"Association, sport, culture\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fresque des fronti\u00e8res plan\u00e9taires - 15 octobre 2025 - Amicale La\u00efque des Marsauderies\" \/>\n<meta property=\"og:description\" content=\"Association, sport, culture\" \/>\n<meta property=\"og:url\" content=\"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Amicale La\u00efque des Marsauderies\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T20:34:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T20:36:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/09\/Fresque_frontieres_planetaires.png\" \/>\n\t<meta property=\"og:image:width\" content=\"298\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dominique Partenay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dominique Partenay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/\"},\"author\":{\"name\":\"Dominique Partenay\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#\\\/schema\\\/person\\\/c728d631e895f3b0f4cb8a1fad1069c3\"},\"headline\":\"La Fresque des fronti\u00e8res plan\u00e9taires &#8211; 15 octobre 2025\",\"datePublished\":\"2025-09-26T20:34:03+00:00\",\"dateModified\":\"2025-09-26T20:36:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/\"},\"wordCount\":214,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Fresque_frontieres_planetaires.png\",\"articleSection\":[\"Activit\u00e9s\",\"Manifestations\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/\",\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/\",\"name\":\"La Fresque des fronti\u00e8res plan\u00e9taires - 15 octobre 2025 - Amicale La\u00efque des Marsauderies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Fresque_frontieres_planetaires.png\",\"datePublished\":\"2025-09-26T20:34:03+00:00\",\"dateModified\":\"2025-09-26T20:36:09+00:00\",\"description\":\"Association, sport, culture\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Fresque_frontieres_planetaires.png\",\"contentUrl\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Fresque_frontieres_planetaires.png\",\"width\":298,\"height\":169},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/2025\\\/09\\\/26\\\/la-fresque-des-frontieres-planetaires-15-octobre-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fresque des fronti\u00e8res plan\u00e9taires &#8211; 15 octobre 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#website\",\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/\",\"name\":\"Amicale La\u00efque des Marsauderies\",\"description\":\"Sport pour tous et \u00e9ducation populaire\",\"publisher\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#organization\",\"name\":\"Amicale Laique des Marsauderies\",\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-UFOLEP.png\",\"contentUrl\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-UFOLEP.png\",\"width\":320,\"height\":244,\"caption\":\"Amicale Laique des Marsauderies\"},\"image\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#\\\/schema\\\/person\\\/c728d631e895f3b0f4cb8a1fad1069c3\",\"name\":\"Dominique Partenay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44edc2e321b05e8ba749554d00ba04c9521aab4762cae8fa0e0c51d91d17c5ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44edc2e321b05e8ba749554d00ba04c9521aab4762cae8fa0e0c51d91d17c5ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44edc2e321b05e8ba749554d00ba04c9521aab4762cae8fa0e0c51d91d17c5ef?s=96&d=mm&r=g\",\"caption\":\"Dominique Partenay\"},\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/author\\\/partenay-d\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fresque des fronti\u00e8res plan\u00e9taires - 15 octobre 2025 - Amicale La\u00efque des Marsauderies","description":"Association, sport, culture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"La Fresque des fronti\u00e8res plan\u00e9taires - 15 octobre 2025 - Amicale La\u00efque des Marsauderies","og_description":"Association, sport, culture","og_url":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/","og_site_name":"Amicale La\u00efque des Marsauderies","article_published_time":"2025-09-26T20:34:03+00:00","article_modified_time":"2025-09-26T20:36:09+00:00","og_image":[{"width":298,"height":169,"url":"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/09\/Fresque_frontieres_planetaires.png","type":"image\/png"}],"author":"Dominique Partenay","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dominique Partenay","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/#article","isPartOf":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/"},"author":{"name":"Dominique Partenay","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#\/schema\/person\/c728d631e895f3b0f4cb8a1fad1069c3"},"headline":"La Fresque des fronti\u00e8res plan\u00e9taires &#8211; 15 octobre 2025","datePublished":"2025-09-26T20:34:03+00:00","dateModified":"2025-09-26T20:36:09+00:00","mainEntityOfPage":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/"},"wordCount":214,"commentCount":0,"publisher":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#organization"},"image":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/09\/Fresque_frontieres_planetaires.png","articleSection":["Activit\u00e9s","Manifestations"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/","url":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/","name":"La Fresque des fronti\u00e8res plan\u00e9taires - 15 octobre 2025 - Amicale La\u00efque des Marsauderies","isPartOf":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/#primaryimage"},"image":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/09\/Fresque_frontieres_planetaires.png","datePublished":"2025-09-26T20:34:03+00:00","dateModified":"2025-09-26T20:36:09+00:00","description":"Association, sport, culture","breadcrumb":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/#primaryimage","url":"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/09\/Fresque_frontieres_planetaires.png","contentUrl":"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2025\/09\/Fresque_frontieres_planetaires.png","width":298,"height":169},{"@type":"BreadcrumbList","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/2025\/09\/26\/la-fresque-des-frontieres-planetaires-15-octobre-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/al-nanteserdre.org\/alm-wp\/"},{"@type":"ListItem","position":2,"name":"La Fresque des fronti\u00e8res plan\u00e9taires &#8211; 15 octobre 2025"}]},{"@type":"WebSite","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#website","url":"https:\/\/al-nanteserdre.org\/alm-wp\/","name":"Amicale La\u00efque des Marsauderies","description":"Sport pour tous et \u00e9ducation populaire","publisher":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/al-nanteserdre.org\/alm-wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#organization","name":"Amicale Laique des Marsauderies","url":"https:\/\/al-nanteserdre.org\/alm-wp\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#\/schema\/logo\/image\/","url":"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2023\/04\/Logo-UFOLEP.png","contentUrl":"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2023\/04\/Logo-UFOLEP.png","width":320,"height":244,"caption":"Amicale Laique des Marsauderies"},"image":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#\/schema\/person\/c728d631e895f3b0f4cb8a1fad1069c3","name":"Dominique Partenay","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/44edc2e321b05e8ba749554d00ba04c9521aab4762cae8fa0e0c51d91d17c5ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44edc2e321b05e8ba749554d00ba04c9521aab4762cae8fa0e0c51d91d17c5ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44edc2e321b05e8ba749554d00ba04c9521aab4762cae8fa0e0c51d91d17c5ef?s=96&d=mm&r=g","caption":"Dominique Partenay"},"url":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/author\/partenay-d\/"}]}},"_links":{"self":[{"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/posts\/3264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/comments?post=3264"}],"version-history":[{"count":2,"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/posts\/3264\/revisions"}],"predecessor-version":[{"id":3267,"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/posts\/3264\/revisions\/3267"}],"wp:attachment":[{"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/media?parent=3264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/categories?post=3264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/tags?post=3264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}