{"id":3,"count":6,"description":"Toutes les informations concernant l'Amicale.","link":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/category\/uncategorized\/","name":"Actualit\u00e9s","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Actualit\u00e9s - Amicale La\u00efque des Marsauderies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/category\/uncategorized\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Actualit\u00e9s - Amicale La\u00efque des Marsauderies\" \/>\n<meta property=\"og:description\" content=\"Toutes les informations concernant l&rsquo;Amicale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/category\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"Amicale La\u00efque des Marsauderies\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/category\\\/uncategorized\\\/\",\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/category\\\/uncategorized\\\/\",\"name\":\"Archives des Actualit\u00e9s - Amicale La\u00efque des Marsauderies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/category\\\/uncategorized\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/index.php\\\/category\\\/uncategorized\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#website\",\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/\",\"name\":\"Amicale La\u00efque des Marsauderies\",\"description\":\"Sport pour tous et \u00e9ducation populaire\",\"publisher\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#organization\",\"name\":\"Amicale Laique des Marsauderies\",\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-UFOLEP.png\",\"contentUrl\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-UFOLEP.png\",\"width\":320,\"height\":244,\"caption\":\"Amicale Laique des Marsauderies\"},\"image\":{\"@id\":\"https:\\\/\\\/al-nanteserdre.org\\\/alm-wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Actualit\u00e9s - Amicale La\u00efque des Marsauderies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/category\/uncategorized\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Actualit\u00e9s - Amicale La\u00efque des Marsauderies","og_description":"Toutes les informations concernant l&rsquo;Amicale.","og_url":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/category\/uncategorized\/","og_site_name":"Amicale La\u00efque des Marsauderies","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/category\/uncategorized\/","url":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/category\/uncategorized\/","name":"Archives des Actualit\u00e9s - Amicale La\u00efque des Marsauderies","isPartOf":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#website"},"breadcrumb":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/category\/uncategorized\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/category\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/al-nanteserdre.org\/alm-wp\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#website","url":"https:\/\/al-nanteserdre.org\/alm-wp\/","name":"Amicale La\u00efque des Marsauderies","description":"Sport pour tous et \u00e9ducation populaire","publisher":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/al-nanteserdre.org\/alm-wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#organization","name":"Amicale Laique des Marsauderies","url":"https:\/\/al-nanteserdre.org\/alm-wp\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#\/schema\/logo\/image\/","url":"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2023\/04\/Logo-UFOLEP.png","contentUrl":"https:\/\/al-nanteserdre.org\/alm-wp\/wp-content\/uploads\/2023\/04\/Logo-UFOLEP.png","width":320,"height":244,"caption":"Amicale Laique des Marsauderies"},"image":{"@id":"https:\/\/al-nanteserdre.org\/alm-wp\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/al-nanteserdre.org\/alm-wp\/index.php\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}